{"id":6963,"date":"2026-05-13T11:24:57","date_gmt":"2026-05-13T15:24:57","guid":{"rendered":"https:\/\/www.trincoll.edu\/reporter\/?page_id=6963"},"modified":"2026-05-13T11:24:57","modified_gmt":"2026-05-13T15:24:57","slug":"winter-2022","status":"publish","type":"page","link":"https:\/\/www.trincoll.edu\/reporter\/winter-2022\/","title":{"rendered":"The Trinity Reporter Winter 2022"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":139,"featured_media":0,"parent":0,"menu_order":13,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-6963","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.5 (Yoast SEO v25.8) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>The Trinity Reporter Winter 2022 - The Trinity Reporter<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.trincoll.edu\/reporter\/winter-2022\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Trinity Reporter Winter 2022\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.trincoll.edu\/reporter\/winter-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"The Trinity Reporter\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.trincoll.edu\/reporter\/winter-2022\/\",\"url\":\"https:\/\/www.trincoll.edu\/reporter\/winter-2022\/\",\"name\":\"The Trinity Reporter Winter 2022 - The Trinity Reporter\",\"isPartOf\":{\"@id\":\"https:\/\/www.trincoll.edu\/reporter\/#website\"},\"datePublished\":\"2026-05-13T15:24:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.trincoll.edu\/reporter\/winter-2022\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.trincoll.edu\/reporter\/winter-2022\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.trincoll.edu\/reporter\/winter-2022\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.trincoll.edu\/reporter\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Trinity Reporter Winter 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.trincoll.edu\/reporter\/#website\",\"url\":\"https:\/\/www.trincoll.edu\/reporter\/\",\"name\":\"The Trinity Reporter\",\"description\":\"The Trinity College alumni magazine\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.trincoll.edu\/reporter\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"The Trinity Reporter Winter 2022 - The Trinity Reporter","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.trincoll.edu\/reporter\/winter-2022\/","og_locale":"en_US","og_type":"article","og_title":"The Trinity Reporter Winter 2022","og_url":"https:\/\/www.trincoll.edu\/reporter\/winter-2022\/","og_site_name":"The Trinity Reporter","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.trincoll.edu\/reporter\/winter-2022\/","url":"https:\/\/www.trincoll.edu\/reporter\/winter-2022\/","name":"The Trinity Reporter Winter 2022 - The Trinity Reporter","isPartOf":{"@id":"https:\/\/www.trincoll.edu\/reporter\/#website"},"datePublished":"2026-05-13T15:24:57+00:00","breadcrumb":{"@id":"https:\/\/www.trincoll.edu\/reporter\/winter-2022\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.trincoll.edu\/reporter\/winter-2022\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.trincoll.edu\/reporter\/winter-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.trincoll.edu\/reporter\/"},{"@type":"ListItem","position":2,"name":"The Trinity Reporter Winter 2022"}]},{"@type":"WebSite","@id":"https:\/\/www.trincoll.edu\/reporter\/#website","url":"https:\/\/www.trincoll.edu\/reporter\/","name":"The Trinity Reporter","description":"The Trinity College alumni magazine","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.trincoll.edu\/reporter\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.trincoll.edu\/reporter\/wp-json\/wp\/v2\/pages\/6963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.trincoll.edu\/reporter\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.trincoll.edu\/reporter\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.trincoll.edu\/reporter\/wp-json\/wp\/v2\/users\/139"}],"replies":[{"embeddable":true,"href":"https:\/\/www.trincoll.edu\/reporter\/wp-json\/wp\/v2\/comments?post=6963"}],"version-history":[{"count":2,"href":"https:\/\/www.trincoll.edu\/reporter\/wp-json\/wp\/v2\/pages\/6963\/revisions"}],"predecessor-version":[{"id":7207,"href":"https:\/\/www.trincoll.edu\/reporter\/wp-json\/wp\/v2\/pages\/6963\/revisions\/7207"}],"wp:attachment":[{"href":"https:\/\/www.trincoll.edu\/reporter\/wp-json\/wp\/v2\/media?parent=6963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}